{"id":1893,"date":"2025-11-10T14:53:26","date_gmt":"2025-11-10T14:53:26","guid":{"rendered":"https:\/\/idc-clinic.connectionthemes.com\/especialidades\/reeducation-buccale\/branqueamento-dentario\/"},"modified":"2026-01-21T15:20:58","modified_gmt":"2026-01-21T15:20:58","slug":"blanchiment-des-dents","status":"publish","type":"service","link":"http:\/\/13.38.59.60\/fr\/specialites\/reeducation-buccale\/blanchiment-des-dents\/","title":{"rendered":"Blanchiment des dents"},"content":{"rendered":"","protected":false},"featured_media":1894,"parent":1679,"menu_order":14,"template":"","specialties":[],"class_list":["post-1893","service","type-service","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Blanchiment des dents - IDC.Clinic<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/idc.clinic\/specialites\/reabilitacao-oral\/branqueamento-dentario\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blanchiment des dents - IDC.Clinic\" \/>\n<meta property=\"og:url\" content=\"https:\/\/idc.clinic\/specialites\/reabilitacao-oral\/branqueamento-dentario\/\" \/>\n<meta property=\"og:site_name\" content=\"IDC.Clinic\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-21T15:20:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/idc.clinic\/wp-content\/uploads\/2025\/11\/01_Branqueamento.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1520\" \/>\n\t<meta property=\"og:image:height\" content=\"730\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/idc.clinic\\\/specialites\\\/reabilitacao-oral\\\/branqueamento-dentario\\\/\",\"url\":\"https:\\\/\\\/idc.clinic\\\/specialites\\\/reabilitacao-oral\\\/branqueamento-dentario\\\/\",\"name\":\"Blanchiment des dents - IDC.Clinic\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/idc.clinic\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/idc.clinic\\\/specialites\\\/reabilitacao-oral\\\/branqueamento-dentario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/idc.clinic\\\/specialites\\\/reabilitacao-oral\\\/branqueamento-dentario\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/13.38.59.60\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/01_Branqueamento.png\",\"datePublished\":\"2025-11-10T14:53:26+00:00\",\"dateModified\":\"2026-01-21T15:20:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/idc.clinic\\\/specialites\\\/reabilitacao-oral\\\/branqueamento-dentario\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/idc.clinic\\\/specialites\\\/reabilitacao-oral\\\/branqueamento-dentario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/idc.clinic\\\/specialites\\\/reabilitacao-oral\\\/branqueamento-dentario\\\/#primaryimage\",\"url\":\"http:\\\/\\\/13.38.59.60\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/01_Branqueamento.png\",\"contentUrl\":\"http:\\\/\\\/13.38.59.60\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/01_Branqueamento.png\",\"width\":1520,\"height\":730},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/idc.clinic\\\/specialites\\\/reabilitacao-oral\\\/branqueamento-dentario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/idc.clinic\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9\u00e9ducation buccale\",\"item\":\"https:\\\/\\\/idc.clinic\\\/specialites\\\/reabilitacao-oral\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Blanchiment des dents\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/idc.clinic\\\/#website\",\"url\":\"https:\\\/\\\/idc.clinic\\\/\",\"name\":\"idc\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/idc.clinic\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/idc.clinic\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/idc.clinic\\\/#organization\",\"name\":\"idc\",\"url\":\"https:\\\/\\\/idc.clinic\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/idc.clinic\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/13.38.59.60\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/new-logo.png\",\"contentUrl\":\"http:\\\/\\\/13.38.59.60\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/new-logo.png\",\"width\":1650,\"height\":686,\"caption\":\"idc\"},\"image\":{\"@id\":\"https:\\\/\\\/idc.clinic\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blanchiment des dents - IDC.Clinic","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/idc.clinic\/specialites\/reabilitacao-oral\/branqueamento-dentario\/","og_locale":"fr_FR","og_type":"article","og_title":"Blanchiment des dents - IDC.Clinic","og_url":"https:\/\/idc.clinic\/specialites\/reabilitacao-oral\/branqueamento-dentario\/","og_site_name":"IDC.Clinic","article_modified_time":"2026-01-21T15:20:58+00:00","og_image":[{"width":1520,"height":730,"url":"https:\/\/idc.clinic\/wp-content\/uploads\/2025\/11\/01_Branqueamento.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/idc.clinic\/specialites\/reabilitacao-oral\/branqueamento-dentario\/","url":"https:\/\/idc.clinic\/specialites\/reabilitacao-oral\/branqueamento-dentario\/","name":"Blanchiment des dents - IDC.Clinic","isPartOf":{"@id":"https:\/\/idc.clinic\/#website"},"primaryImageOfPage":{"@id":"https:\/\/idc.clinic\/specialites\/reabilitacao-oral\/branqueamento-dentario\/#primaryimage"},"image":{"@id":"https:\/\/idc.clinic\/specialites\/reabilitacao-oral\/branqueamento-dentario\/#primaryimage"},"thumbnailUrl":"http:\/\/13.38.59.60\/wp-content\/uploads\/2025\/11\/01_Branqueamento.png","datePublished":"2025-11-10T14:53:26+00:00","dateModified":"2026-01-21T15:20:58+00:00","breadcrumb":{"@id":"https:\/\/idc.clinic\/specialites\/reabilitacao-oral\/branqueamento-dentario\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/idc.clinic\/specialites\/reabilitacao-oral\/branqueamento-dentario\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/idc.clinic\/specialites\/reabilitacao-oral\/branqueamento-dentario\/#primaryimage","url":"http:\/\/13.38.59.60\/wp-content\/uploads\/2025\/11\/01_Branqueamento.png","contentUrl":"http:\/\/13.38.59.60\/wp-content\/uploads\/2025\/11\/01_Branqueamento.png","width":1520,"height":730},{"@type":"BreadcrumbList","@id":"https:\/\/idc.clinic\/specialites\/reabilitacao-oral\/branqueamento-dentario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/idc.clinic\/fr\/"},{"@type":"ListItem","position":2,"name":"R\u00e9\u00e9ducation buccale","item":"https:\/\/idc.clinic\/specialites\/reabilitacao-oral\/"},{"@type":"ListItem","position":3,"name":"Blanchiment des dents"}]},{"@type":"WebSite","@id":"https:\/\/idc.clinic\/#website","url":"https:\/\/idc.clinic\/","name":"idc","description":"","publisher":{"@id":"https:\/\/idc.clinic\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/idc.clinic\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/idc.clinic\/#organization","name":"idc","url":"https:\/\/idc.clinic\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/idc.clinic\/#\/schema\/logo\/image\/","url":"http:\/\/13.38.59.60\/wp-content\/uploads\/2026\/02\/new-logo.png","contentUrl":"http:\/\/13.38.59.60\/wp-content\/uploads\/2026\/02\/new-logo.png","width":1650,"height":686,"caption":"idc"},"image":{"@id":"https:\/\/idc.clinic\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"http:\/\/13.38.59.60\/fr\/wp-json\/wp\/v2\/service\/1893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/13.38.59.60\/fr\/wp-json\/wp\/v2\/service"}],"about":[{"href":"http:\/\/13.38.59.60\/fr\/wp-json\/wp\/v2\/types\/service"}],"up":[{"embeddable":true,"href":"http:\/\/13.38.59.60\/fr\/wp-json\/wp\/v2\/service\/1679"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/13.38.59.60\/fr\/wp-json\/wp\/v2\/media\/1894"}],"wp:attachment":[{"href":"http:\/\/13.38.59.60\/fr\/wp-json\/wp\/v2\/media?parent=1893"}],"wp:term":[{"taxonomy":"specialties","embeddable":true,"href":"http:\/\/13.38.59.60\/fr\/wp-json\/wp\/v2\/specialties?post=1893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}