{"id":1685,"date":"2025-11-12T08:15:42","date_gmt":"2025-11-12T08:15:42","guid":{"rendered":"https:\/\/idc-clinic.connectionthemes.com\/especialidades\/reabilitacao-oral\/higiene-oral\/"},"modified":"2026-01-22T08:34:57","modified_gmt":"2026-01-22T08:34:57","slug":"oral-hygiene","status":"publish","type":"service","link":"http:\/\/13.38.59.60\/en\/speciality\/oral-rehabilitation\/oral-hygiene\/","title":{"rendered":"Oral Hygiene"},"content":{"rendered":"","protected":false},"featured_media":1686,"parent":1677,"menu_order":29,"template":"","specialties":[33],"class_list":["post-1685","service","type-service","status-publish","has-post-thumbnail","hentry","specialties-dentaria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oral Hygiene - IDC.Clinic<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/idc.clinic\/en\/speciality\/oral-rehabilitation\/oral-hygiene\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oral Hygiene - IDC.Clinic\" \/>\n<meta property=\"og:url\" content=\"https:\/\/idc.clinic\/en\/speciality\/oral-rehabilitation\/oral-hygiene\/\" \/>\n<meta property=\"og:site_name\" content=\"IDC.Clinic\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-22T08:34:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/idc.clinic\/wp-content\/uploads\/2025\/11\/01_Higiene-Oral.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1520\" \/>\n\t<meta property=\"og:image:height\" content=\"730\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/idc.clinic\\\/en\\\/speciality\\\/oral-rehabilitation\\\/oral-hygiene\\\/\",\"url\":\"https:\\\/\\\/idc.clinic\\\/en\\\/speciality\\\/oral-rehabilitation\\\/oral-hygiene\\\/\",\"name\":\"Oral Hygiene - IDC.Clinic\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/idc.clinic\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/idc.clinic\\\/en\\\/speciality\\\/oral-rehabilitation\\\/oral-hygiene\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/idc.clinic\\\/en\\\/speciality\\\/oral-rehabilitation\\\/oral-hygiene\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/13.38.59.60\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/01_Higiene-Oral.png\",\"datePublished\":\"2025-11-12T08:15:42+00:00\",\"dateModified\":\"2026-01-22T08:34:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/idc.clinic\\\/en\\\/speciality\\\/oral-rehabilitation\\\/oral-hygiene\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/idc.clinic\\\/en\\\/speciality\\\/oral-rehabilitation\\\/oral-hygiene\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/idc.clinic\\\/en\\\/speciality\\\/oral-rehabilitation\\\/oral-hygiene\\\/#primaryimage\",\"url\":\"http:\\\/\\\/13.38.59.60\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/01_Higiene-Oral.png\",\"contentUrl\":\"http:\\\/\\\/13.38.59.60\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/01_Higiene-Oral.png\",\"width\":1520,\"height\":730},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/idc.clinic\\\/en\\\/speciality\\\/oral-rehabilitation\\\/oral-hygiene\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/idc.clinic\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oral Rehabilitation\",\"item\":\"https:\\\/\\\/idc.clinic\\\/en\\\/speciality\\\/oral-rehabilitation\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Oral Hygiene\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/idc.clinic\\\/#website\",\"url\":\"https:\\\/\\\/idc.clinic\\\/\",\"name\":\"idc\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/idc.clinic\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/idc.clinic\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/idc.clinic\\\/#organization\",\"name\":\"idc\",\"url\":\"https:\\\/\\\/idc.clinic\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/idc.clinic\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/13.38.59.60\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/new-logo.png\",\"contentUrl\":\"http:\\\/\\\/13.38.59.60\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/new-logo.png\",\"width\":1650,\"height\":686,\"caption\":\"idc\"},\"image\":{\"@id\":\"https:\\\/\\\/idc.clinic\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oral Hygiene - IDC.Clinic","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/idc.clinic\/en\/speciality\/oral-rehabilitation\/oral-hygiene\/","og_locale":"en_US","og_type":"article","og_title":"Oral Hygiene - IDC.Clinic","og_url":"https:\/\/idc.clinic\/en\/speciality\/oral-rehabilitation\/oral-hygiene\/","og_site_name":"IDC.Clinic","article_modified_time":"2026-01-22T08:34:57+00:00","og_image":[{"width":1520,"height":730,"url":"https:\/\/idc.clinic\/wp-content\/uploads\/2025\/11\/01_Higiene-Oral.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/idc.clinic\/en\/speciality\/oral-rehabilitation\/oral-hygiene\/","url":"https:\/\/idc.clinic\/en\/speciality\/oral-rehabilitation\/oral-hygiene\/","name":"Oral Hygiene - IDC.Clinic","isPartOf":{"@id":"https:\/\/idc.clinic\/#website"},"primaryImageOfPage":{"@id":"https:\/\/idc.clinic\/en\/speciality\/oral-rehabilitation\/oral-hygiene\/#primaryimage"},"image":{"@id":"https:\/\/idc.clinic\/en\/speciality\/oral-rehabilitation\/oral-hygiene\/#primaryimage"},"thumbnailUrl":"http:\/\/13.38.59.60\/wp-content\/uploads\/2025\/11\/01_Higiene-Oral.png","datePublished":"2025-11-12T08:15:42+00:00","dateModified":"2026-01-22T08:34:57+00:00","breadcrumb":{"@id":"https:\/\/idc.clinic\/en\/speciality\/oral-rehabilitation\/oral-hygiene\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/idc.clinic\/en\/speciality\/oral-rehabilitation\/oral-hygiene\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/idc.clinic\/en\/speciality\/oral-rehabilitation\/oral-hygiene\/#primaryimage","url":"http:\/\/13.38.59.60\/wp-content\/uploads\/2025\/11\/01_Higiene-Oral.png","contentUrl":"http:\/\/13.38.59.60\/wp-content\/uploads\/2025\/11\/01_Higiene-Oral.png","width":1520,"height":730},{"@type":"BreadcrumbList","@id":"https:\/\/idc.clinic\/en\/speciality\/oral-rehabilitation\/oral-hygiene\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/idc.clinic\/en\/"},{"@type":"ListItem","position":2,"name":"Oral Rehabilitation","item":"https:\/\/idc.clinic\/en\/speciality\/oral-rehabilitation\/"},{"@type":"ListItem","position":3,"name":"Oral Hygiene"}]},{"@type":"WebSite","@id":"https:\/\/idc.clinic\/#website","url":"https:\/\/idc.clinic\/","name":"idc","description":"","publisher":{"@id":"https:\/\/idc.clinic\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/idc.clinic\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/idc.clinic\/#organization","name":"idc","url":"https:\/\/idc.clinic\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/idc.clinic\/#\/schema\/logo\/image\/","url":"http:\/\/13.38.59.60\/wp-content\/uploads\/2026\/02\/new-logo.png","contentUrl":"http:\/\/13.38.59.60\/wp-content\/uploads\/2026\/02\/new-logo.png","width":1650,"height":686,"caption":"idc"},"image":{"@id":"https:\/\/idc.clinic\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"http:\/\/13.38.59.60\/en\/wp-json\/wp\/v2\/service\/1685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/13.38.59.60\/en\/wp-json\/wp\/v2\/service"}],"about":[{"href":"http:\/\/13.38.59.60\/en\/wp-json\/wp\/v2\/types\/service"}],"up":[{"embeddable":true,"href":"http:\/\/13.38.59.60\/en\/wp-json\/wp\/v2\/service\/1677"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/13.38.59.60\/en\/wp-json\/wp\/v2\/media\/1686"}],"wp:attachment":[{"href":"http:\/\/13.38.59.60\/en\/wp-json\/wp\/v2\/media?parent=1685"}],"wp:term":[{"taxonomy":"specialties","embeddable":true,"href":"http:\/\/13.38.59.60\/en\/wp-json\/wp\/v2\/specialties?post=1685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}