{"id":1639,"date":"2025-11-12T14:19:40","date_gmt":"2025-11-12T14:19:40","guid":{"rendered":"https:\/\/idc-clinic.connectionthemes.com\/especialidades\/microneedling\/"},"modified":"2026-01-22T08:53:56","modified_gmt":"2026-01-22T08:53:56","slug":"microneedling","status":"publish","type":"service","link":"http:\/\/13.38.59.60\/en\/speciality\/microneedling\/","title":{"rendered":"Microneedling"},"content":{"rendered":"","protected":false},"featured_media":1640,"parent":0,"menu_order":55,"template":"","specialties":[31],"class_list":["post-1639","service","type-service","status-publish","has-post-thumbnail","hentry","specialties-med-estetica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Microneedling - IDC.Clinic<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/idc.clinic\/speciality\/microneedling\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Microneedling - IDC.Clinic\" \/>\n<meta property=\"og:url\" content=\"https:\/\/idc.clinic\/speciality\/microneedling\/\" \/>\n<meta property=\"og:site_name\" content=\"IDC.Clinic\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-22T08:53:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/idc.clinic\/wp-content\/uploads\/2025\/11\/01_Microneedling.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1064\" \/>\n\t<meta property=\"og:image:height\" content=\"510\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/idc.clinic\\\/speciality\\\/microneedling\\\/\",\"url\":\"https:\\\/\\\/idc.clinic\\\/speciality\\\/microneedling\\\/\",\"name\":\"Microneedling - IDC.Clinic\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/idc.clinic\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/idc.clinic\\\/speciality\\\/microneedling\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/idc.clinic\\\/speciality\\\/microneedling\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/13.38.59.60\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/01_Microneedling.jpg\",\"datePublished\":\"2025-11-12T14:19:40+00:00\",\"dateModified\":\"2026-01-22T08:53:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/idc.clinic\\\/speciality\\\/microneedling\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/idc.clinic\\\/speciality\\\/microneedling\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/idc.clinic\\\/speciality\\\/microneedling\\\/#primaryimage\",\"url\":\"http:\\\/\\\/13.38.59.60\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/01_Microneedling.jpg\",\"contentUrl\":\"http:\\\/\\\/13.38.59.60\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/01_Microneedling.jpg\",\"width\":1064,\"height\":510},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/idc.clinic\\\/speciality\\\/microneedling\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/idc.clinic\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Microneedling\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/idc.clinic\\\/#website\",\"url\":\"https:\\\/\\\/idc.clinic\\\/\",\"name\":\"idc\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/idc.clinic\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/idc.clinic\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/idc.clinic\\\/#organization\",\"name\":\"idc\",\"url\":\"https:\\\/\\\/idc.clinic\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/idc.clinic\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/13.38.59.60\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/new-logo.png\",\"contentUrl\":\"http:\\\/\\\/13.38.59.60\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/new-logo.png\",\"width\":1650,\"height\":686,\"caption\":\"idc\"},\"image\":{\"@id\":\"https:\\\/\\\/idc.clinic\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Microneedling - IDC.Clinic","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/idc.clinic\/speciality\/microneedling\/","og_locale":"en_US","og_type":"article","og_title":"Microneedling - IDC.Clinic","og_url":"https:\/\/idc.clinic\/speciality\/microneedling\/","og_site_name":"IDC.Clinic","article_modified_time":"2026-01-22T08:53:56+00:00","og_image":[{"width":1064,"height":510,"url":"https:\/\/idc.clinic\/wp-content\/uploads\/2025\/11\/01_Microneedling.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/idc.clinic\/speciality\/microneedling\/","url":"https:\/\/idc.clinic\/speciality\/microneedling\/","name":"Microneedling - IDC.Clinic","isPartOf":{"@id":"https:\/\/idc.clinic\/#website"},"primaryImageOfPage":{"@id":"https:\/\/idc.clinic\/speciality\/microneedling\/#primaryimage"},"image":{"@id":"https:\/\/idc.clinic\/speciality\/microneedling\/#primaryimage"},"thumbnailUrl":"http:\/\/13.38.59.60\/wp-content\/uploads\/2025\/11\/01_Microneedling.jpg","datePublished":"2025-11-12T14:19:40+00:00","dateModified":"2026-01-22T08:53:56+00:00","breadcrumb":{"@id":"https:\/\/idc.clinic\/speciality\/microneedling\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/idc.clinic\/speciality\/microneedling\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/idc.clinic\/speciality\/microneedling\/#primaryimage","url":"http:\/\/13.38.59.60\/wp-content\/uploads\/2025\/11\/01_Microneedling.jpg","contentUrl":"http:\/\/13.38.59.60\/wp-content\/uploads\/2025\/11\/01_Microneedling.jpg","width":1064,"height":510},{"@type":"BreadcrumbList","@id":"https:\/\/idc.clinic\/speciality\/microneedling\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/idc.clinic\/en\/"},{"@type":"ListItem","position":2,"name":"Microneedling"}]},{"@type":"WebSite","@id":"https:\/\/idc.clinic\/#website","url":"https:\/\/idc.clinic\/","name":"idc","description":"","publisher":{"@id":"https:\/\/idc.clinic\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/idc.clinic\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/idc.clinic\/#organization","name":"idc","url":"https:\/\/idc.clinic\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/idc.clinic\/#\/schema\/logo\/image\/","url":"http:\/\/13.38.59.60\/wp-content\/uploads\/2026\/02\/new-logo.png","contentUrl":"http:\/\/13.38.59.60\/wp-content\/uploads\/2026\/02\/new-logo.png","width":1650,"height":686,"caption":"idc"},"image":{"@id":"https:\/\/idc.clinic\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"http:\/\/13.38.59.60\/en\/wp-json\/wp\/v2\/service\/1639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/13.38.59.60\/en\/wp-json\/wp\/v2\/service"}],"about":[{"href":"http:\/\/13.38.59.60\/en\/wp-json\/wp\/v2\/types\/service"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/13.38.59.60\/en\/wp-json\/wp\/v2\/media\/1640"}],"wp:attachment":[{"href":"http:\/\/13.38.59.60\/en\/wp-json\/wp\/v2\/media?parent=1639"}],"wp:term":[{"taxonomy":"specialties","embeddable":true,"href":"http:\/\/13.38.59.60\/en\/wp-json\/wp\/v2\/specialties?post=1639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}